{"id":28413,"date":"2025-12-01T08:18:40","date_gmt":"2025-12-01T07:18:40","guid":{"rendered":"https:\/\/dus4you.de\/index.php\/2025\/12\/01\/was-nun-fortuna-14857917\/"},"modified":"2026-05-04T08:42:34","modified_gmt":"2026-05-04T06:42:34","slug":"was-nun-fortuna-14857917","status":"publish","type":"post","link":"https:\/\/dus4you.de\/index.php\/2025\/12\/01\/was-nun-fortuna-14857917\/","title":{"rendered":"\ud83d\udd34\u26aa Was nun Fortuna?\ud83d\udd34\u26aa"},"content":{"rendered":"<figure class=\"d4yni-figure d4yni-figure-local\"><a href=\"https:\/\/dus4you.de\/wp-content\/uploads\/2025\/12\/d4y-f09f94b4e29aaa-was-nun-fortunaf09f94b4e29aaa-dezember.2025-2.jpg\" class=\"d4yni-lightbox\"><img decoding=\"async\" src=\"https:\/\/dus4you.de\/wp-content\/uploads\/2025\/12\/d4y-f09f94b4e29aaa-was-nun-fortunaf09f94b4e29aaa-dezember.2025-2.jpg\" alt=\"\" loading=\"lazy\"><\/a><\/figure>\n<p>\ud83d\udd34\u26aa Was nun Fortuna?\ud83d\udd34\u26aa<\/p>\n<p>Sportlich ist das in Dresden schnell erz\u00e4hlt: 1:2 verloren, zu wenig Durchschlagskraft, zu wenig Kontrolle \u2013 und wieder wirkt es, als w\u00fcrde Fortuna erst aufwachen, wenn das Spiel schon wegkippt. Entscheidend ist diesmal aber etwas anderes:<\/p>\n<p>0 Reaktionen. 0 Richtung. 0 Erkl\u00e4rung.<br>\nKein klares Signal, wof\u00fcr dieser Kurs steht \u2013 und wie man ihn korrigieren will.<\/p>\n<p>Die Trainer-Personalie wird unterschiedlich bewertet, deshalb geht\u2019s uns nicht um Lagerbildung, sondern um Verantwortung und F\u00fchrung: Warum wirkt dieser ganze Umbruch wie ein Blindflug?<br>\nNach dem massiven Teamumbau und dem Trainerwechsel steht die sportliche Leitung jetzt unter maximalem Druck.<\/p>\n<p>Die Fragen, \u00fcber die unsere Base diskutieren muss:<\/p>\n<p>Wie wollen Allofs und Weber das Ruder rumrei\u00dfen \u2013 ganz konkret?<\/p>\n<p>Gibt es einen Plan f\u00fcr Stabilit\u00e4t, Struktur, Spielidee \u2013 oder nur Durchhalteparolen?<\/p>\n<p>Wie lange h\u00e4lt man an diesem Setup fest, wenn Ergebnisse und Auftritt weiter auseinanderklaffen?<\/p>\n<p>Kommt nach Kader- und Trainerwechsel am Ende auch noch der Managerwechsel?<\/p>\n<p>Und die unangenehmste, aber reale Frage: Wie verhindert man, dass aus Krisenmodus Absturzmodus wird?<\/p>\n<p>Passend dazu: Unsere Aktion \u201eHelden Gesucht\u201c \u2013 denn Fortuna braucht wieder Leute, die Verantwortung sichtbar \u00fcbernehmen:<br>\nhttps:\/\/youtu.be\/3tkVSgJp20Y &lt;- Das Video gerne mal Teilen vielleicht Motiviert das ja?<\/p>\n<p>#FortunaD\u00fcsseldorf #F95 #WasNunFortuna #Fortuna4You #Krise #Allofs #Weber #MarkusAnfang #Teamumbruch #ZweiteLiga #DynamoDresden #F95inDresden #RotWei\u00df #HeldenGesucht<br>\n #95Ole @Follower @Top-Fans<\/p>\n<p><a class=\"button\" href=\"https:\/\/www.facebook.com\/1294036359427179\/posts\/1273062314857917\" target=\"_blank\" rel=\"noopener\">Beitrag auf Facebook ansehen<\/a><\/p>\n\n<div class=\"d4yni-embed d4yni-embed-fbpost\"><div class=\"d4yni-embed-inner\"><iframe src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2F1294036359427179%2Fposts%2F1273062314857917&#038;show_text=false&#038;width=500\" width=\"500\" height=\"680\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\ud83d\udd34\u26aa Was nun Fortuna?\ud83d\udd34\u26aa Sportlich ist das in Dresden schnell erz\u00e4hlt: 1:2 verloren, zu wenig Durchschlagskraft, zu wenig Kontrolle \u2013 und wieder wirkt es, als w\u00fcrde Fortuna erst aufwachen, wenn das Spiel schon wegkippt. Entscheidend ist diesmal aber etwas anderes: 0 Reaktionen. 0 Richtung. 0 Erkl\u00e4rung. Kein klares Signal, wof\u00fcr dieser Kurs steht \u2013 und&hellip; <br \/> <a class=\"button small blue\" href=\"https:\/\/dus4you.de\/index.php\/2025\/12\/01\/was-nun-fortuna-14857917\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":-1,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-28413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fortuna4you","d4yni-imported"],"_links":{"self":[{"href":"https:\/\/dus4you.de\/index.php\/wp-json\/wp\/v2\/posts\/28413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dus4you.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dus4you.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dus4you.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dus4you.de\/index.php\/wp-json\/wp\/v2\/comments?post=28413"}],"version-history":[{"count":3,"href":"https:\/\/dus4you.de\/index.php\/wp-json\/wp\/v2\/posts\/28413\/revisions"}],"predecessor-version":[{"id":29990,"href":"https:\/\/dus4you.de\/index.php\/wp-json\/wp\/v2\/posts\/28413\/revisions\/29990"}],"wp:attachment":[{"href":"https:\/\/dus4you.de\/index.php\/wp-json\/wp\/v2\/media?parent=28413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dus4you.de\/index.php\/wp-json\/wp\/v2\/categories?post=28413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dus4you.de\/index.php\/wp-json\/wp\/v2\/tags?post=28413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}